{"id":534,"date":"2021-08-30T17:05:03","date_gmt":"2021-08-30T17:05:03","guid":{"rendered":"https:\/\/www.antiguorincon.com\/blog\/?p=534"},"modified":"2021-08-28T19:04:11","modified_gmt":"2021-08-28T19:04:11","slug":"descubre-las-terribles-historias-medicas-de-siglos-pasados","status":"publish","type":"post","link":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/","title":{"rendered":"Descubre las terribles historias m\u00e9dicas de siglos pasados"},"content":{"rendered":"\n\t\t\t<!-- START Post 14mayo20 REVOLUTION SLIDER 6.7.34 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_31_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_31_1\" style=\"\" data-version=\"6.7.34\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-113\" data-title=\"prismaticos\" data-anim=\"r:0;\" data-in=\"x:100%;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.antiguorincon.com\/blog\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"dilatadores-uretrales-instrumental-centenario-impresionante-principios-de-1900\" width=\"1024\" height=\"1024\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/dilatadores-uretrales-instrumental-centenario-impresionante-principios-de-1900.jpg\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-115\" data-title=\"localizador\" data-anim=\"r:0;\" data-in=\"x:100%;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.antiguorincon.com\/blog\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"anoscopio-vintage-equipo-medico-rectoscopio-proctoscopio-impresionante\" width=\"1024\" height=\"1024\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/anoscopio-vintage-equipo-medico-rectoscopio-proctoscopio-impresionante.jpg\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-114\" data-title=\"correderas\" data-anim=\"r:0;\" data-in=\"x:100%;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.antiguorincon.com\/blog\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"trepanadores-coleccion-de-trepanadores-desde-los-anos-20-hasta-los-anos-70-taladros-quirurgicos\" width=\"1024\" height=\"1024\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/trepanadores-coleccion-de-trepanadores-desde-los-anos-20-hasta-los-anos-70-taladros-quirurgicos.jpg\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_31_1',rl:[1240,1024,778,480],el:[310],gw:[1240],gh:[310],type:'standard',justify:'',layout:'fullwidth',mh:\"310\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider311\"]!==undefined) {window.RS_MODULES.modules[\"revslider311\"].once = false;window.revapi31 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n<p>En la actualidad, la sanidad es sin\u00f3nimo de salud y progreso, pero si retrocedemos en el tiempo podemos encontrar <b>terribles historias m\u00e9dicas<\/b> capaces de protagonizar nuestras pesadillas durante unas cuantas noches. Artilugios impensables para cualquier tratamiento actual, enfermedades con efectos desastrosos en la piel y consultas con un aspecto espeluznante forman parte de este universo \u00fanico. \u00bfTe atreves a conocerlo?<\/p>\n<h2>El horror de la lepra<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-545 size-medium\" src=\"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/leproso-cabeza-replica-de-monje-leproso-obra-exclusiva-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/leproso-cabeza-replica-de-monje-leproso-obra-exclusiva-300x300.jpg 300w, https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/leproso-cabeza-replica-de-monje-leproso-obra-exclusiva-150x150.jpg 150w, https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/leproso-cabeza-replica-de-monje-leproso-obra-exclusiva-768x768.jpg 768w, https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/leproso-cabeza-replica-de-monje-leproso-obra-exclusiva.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Pocas im\u00e1genes resultan m\u00e1s aterradoras que la de la cabeza de un leproso. La enfermedad de la lepra <b>gangrena los tejidos hasta mutilarlos<\/b>, por lo que las personas afectadas causaban gran horror y rechazo en quienes las ve\u00edan. Adem\u00e1s, su <b>olor era nauseabundo.<\/b><\/p>\n<p>Los efectos f\u00edsicos de la lepra hicieron que esta enfermedad se asociara al <b>mal y al pecado<\/b>. Por eso, muchos leprosos sufrieron verdaderos <b>tormentos<\/b>. En el siglo XIV, un grupo fue acusado de envenenar unos pozos en Francia y condenado a <b>morir en la hoguera<\/b>. Pero no hace falta retroceder tanto en el tiempo para conocer historias de la lepra realmente terribles.<\/p>\n<p>En el siglo XIX, el m\u00e9dico noruego Gerhard Henrik Armauer Hansen se hizo famoso por descubrir el bacilo de la lepra, pero tambi\u00e9n por sus experimentos crueles con estos enfermos. En una de sus terribles historias m\u00e9dicas, lleg\u00f3 a inyectar en un ojo de una paciente un aguja infectada de lepra lepromatosa, la m\u00e1s virulenta de todas.<\/p>\n<h2>Dentistas de miedo<\/h2>\n<p>Una de las <a href=\"https:\/\/www.antiguorincon.com\/profesiones-de-antano-9\">profesiones de anta\u00f1o<\/a> dentro de la medicina que provocaban m\u00e1s miedo en el siglo pasado era la de los<a href=\"https:\/\/www.antiguorincon.com\/dentistas-odontologos-260\"> dentistas<\/a>. Ahora, nos da miedo ir a tratarnos una caries, pero los tratamientos de hace un siglo eran muy diferentes. Caer en las manos de uno de estos personajes sanguinarios, <b>mezcla muchas veces de charlat\u00e1n y m\u00e9dico<\/b>, pod\u00eda acabar en pesadilla.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-543 size-medium\" title=\"terribles historias m\u00e9dicas\" src=\"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/clinica-dental-centenaria-impresionante-unidad-dental-de-epoca-anos-30-300x300.jpg\" alt=\"terribles historias m\u00e9dicas\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/clinica-dental-centenaria-impresionante-unidad-dental-de-epoca-anos-30-300x300.jpg 300w, https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/clinica-dental-centenaria-impresionante-unidad-dental-de-epoca-anos-30-150x150.jpg 150w, https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/clinica-dental-centenaria-impresionante-unidad-dental-de-epoca-anos-30-768x768.jpg 768w, https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/clinica-dental-centenaria-impresionante-unidad-dental-de-epoca-anos-30.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Sentarse en la silla de un dentista de la \u00e9poca no era ninguna garant\u00eda de tranquilidad para muchos pacientes. Y si no, que se lo digan a quienes cayeron en manos de<b> Painless Parker<\/b> quien, en teor\u00eda, apostaba por la odontolog\u00eda sin dolor. Para ello, usaba nada menos que <b>coca\u00edna aguada<\/b>. Ni as\u00ed, logr\u00f3 escapar de terribles historias m\u00e9dicas.<\/p>\n<p>Para promocionarse, decidi\u00f3 hacer un show en el que <strong>extra\u00eda los dientes mientras un m\u00fasico tocaba<\/strong>. De esta manera, no se o\u00edan los gritos de dolor de sus pacientes. Dio un paso m\u00e1s all\u00e1 cuando decidi\u00f3 pasear su silla en una plataforma con caballos, donde ten\u00eda un cubo en el que echaba<b> los dientes que sacaba delante de todo el mundo.<\/b><\/p>\n<h2>Herramientas para terribles historias m\u00e9dicas<\/h2>\n<p>Los <a href=\"https:\/\/www.antiguorincon.com\/medicos-farmaceuticos\">m\u00e9dicos y farmac\u00e9uticos<\/a> antiguos ten\u00edan herramientas que impresionaban solamente con mirarlas por su aspecto, como los anoscopios y proctoscopios. Su dise\u00f1o hace que, si cae uno en tus manos, puedas usarlo como <b>decoraci\u00f3n de una escena de terror.<\/b><\/p>\n<p>Pod\u00edan llegar a medir hasta <b>22 cent\u00edmetros de longitud<\/b>, por lo que una revisi\u00f3n de la zona pod\u00eda convertirse en una verdadera tortura. Mejor no pensar que suced\u00eda si, adem\u00e1s, el m\u00e9dico no era un especialista en el manejo de estos aparatos&#8230;<\/p>\n<h3>Trepanaciones o el arte de agujerear la cabeza<\/h3>\n<p>En el Neol\u00edtico ya se a<b>gujeraban los cr\u00e1neos con objetos punzantes<\/b>, ya fuera como ritual religioso o como tratamiento f\u00edsico. Pasaron los siglos y, aunque parezca surrealista, la idea de trepanar una cabeza sigui\u00f3 vigente hasta la \u00e9poca moderna.<\/p>\n<p>Personas que sufr\u00edan<b> migra\u00f1as o enfermedades como la epilepsia<\/b> pasaban por m\u00e9dicos con <b>taladros <\/b><b>trepanadores<\/b> en sus manos, que pretend\u00edan curarlos. No sabemos si resultaban m\u00e1s pr\u00e1cticos que otras t\u00e9cnicas anteriores, como <strong>ir limando el hueso hasta perforarlo<\/strong> con una superficie granulada, o el movimiento de rotaci\u00f3n que se hac\u00eda para ampliar el agujero cuando se hac\u00eda con un instrumento puntiagudo.<\/p>\n<p>En todo caso, las terribles historias m\u00e9dicas que se produc\u00edan en el quir\u00f3fano eran dignas de una pel\u00edcula de serie B. Aqu\u00ed puedes ver el <a href=\"https:\/\/www.antiguorincon.com\/instrumental-quirurgico-medico-262\">instrumental quir\u00fargico m\u00e9dico<\/a> del pasado.<\/p>\n<h3>Revisiones de pr\u00f3stata<\/h3>\n<p>Los dilatadores uretrales que se usaban hace m\u00e1s o menos un siglo para las exploraciones de pr\u00f3stata eran de un <b>tama\u00f1o espectacularmente grande y estaban hechos de materiales r\u00edgidos<\/b> como el acero. Por lo tanto, eran extremadamente dif\u00edciles de manejar, incluso por los m\u00e9dicos m\u00e1s avezados.<\/p>\n<p>Las <strong>escenas dantescas<\/strong> que se produc\u00edan en la consulta superaban en la mayor\u00eda de ocasiones el dolor que hab\u00eda llevado a los pacientes hasta all\u00ed y los convert\u00eda en verdaderas v\u00edctimas de terribles historias m\u00e9dicas y <b>torturas dignas de la Inquisici\u00f3n.<\/b><\/p>\n<h3>Tratamientos dignos de pel\u00edculas de terror<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-542 size-medium\" title=\"terribles historias m\u00e9dicas\" src=\"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/mesa-quirurgica-para-operaciones-anos-40-impresionante-aparato-cama-hospitalaria-300x300.jpg\" alt=\"terribles historias m\u00e9dicas\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/mesa-quirurgica-para-operaciones-anos-40-impresionante-aparato-cama-hospitalaria-300x300.jpg 300w, https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/mesa-quirurgica-para-operaciones-anos-40-impresionante-aparato-cama-hospitalaria-150x150.jpg 150w, https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/mesa-quirurgica-para-operaciones-anos-40-impresionante-aparato-cama-hospitalaria-768x768.jpg 768w, https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/mesa-quirurgica-para-operaciones-anos-40-impresionante-aparato-cama-hospitalaria.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Una <a href=\"https:\/\/www.antiguorincon.com\/inicio\/mesa-quirurgica-para-operaciones-anos-40-impresionante-aparato-cama-hospitalaria-8934\">mesa de operaciones de un quir\u00f3fano<\/a> de hace 100 a\u00f1os no albergaba ni mucho menos las operaciones de hoy en d\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p>En el siglo XIX, una ni\u00f1a de 12 a\u00f1os de Londres <b>vomit\u00f3 una babosa de jard\u00edn viva<\/b>, despu\u00e9s de quejarse de molestias durante d\u00edas. Y no fue la \u00fanica: lleg\u00f3 a sacar siete m\u00e1s. El m\u00e9dico lo atribuy\u00f3 a la afici\u00f3n de la peque\u00f1a por comer lechugas del jard\u00edn, pero no todos los especialistas opinaban lo mismo.<\/p>\n<p>Otro de los cient\u00edficos que la trat\u00f3 realiz\u00f3 <b>experimentos con babosas vivas mojadas en los \u00e1cidos estomacales<\/b>. Despu\u00e9s de todo el sufrimiento, simplemente decidi\u00f3 que la ni\u00f1a ten\u00eda problemas psicol\u00f3gicos, que le creaban las babosas.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a1Terribles historias m\u00e9dicas para no dormir que, pese a todo nos siguen atrayendo! Desc\u00fabrelas todas en <a href=\"https:\/\/www.antiguorincon.com\"><strong>AntiguoRincon.com<\/strong><\/a>.<\/p>\n<p>Documentalistas de AntiguoRincon.com<\/p>\n<p><strong>\u00bfQuieres publicar tus art\u00edculos o trabajos con tus datos para darte a conocer en nuestro Blog? Env\u00edanoslos a antiguorincon@gmail.com<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la actualidad, la sanidad es sin\u00f3nimo de salud y progreso, pero si retrocedemos en el tiempo podemos encontrar terribles historias m\u00e9dicas capaces de protagonizar nuestras pesadillas durante unas cuantas noches. Artilugios impensables para cualquier tratamiento actual, enfermedades con efectos desastrosos en la piel y consultas con un aspecto espeluznante forman parte de este universo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":552,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,61,49],"tags":[16,65,64,47,63,62],"class_list":["post-534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","category-edad-contemporanea-s-xix-xx","category-historia-de-medicina-historias-medicas","tag-curiosidades-medicas","tag-historia-de-la-medicina","tag-historias-terribles","tag-medicina","tag-medicos","tag-terrible"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Descubre las terribles historias m\u00e9dicas de siglos pasados<\/title>\n<meta name=\"description\" content=\"Te acercamos las terribles historias m\u00e9dicas del pasado. Descubre c\u00f3mo eran las mesas de operaciones, el material de los m\u00e9dicos, etc en nuestro blog.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descubre las terribles historias m\u00e9dicas de siglos pasados\" \/>\n<meta property=\"og:description\" content=\"Te acercamos las terribles historias m\u00e9dicas del pasado. Descubre c\u00f3mo eran las mesas de operaciones, el material de los m\u00e9dicos, etc en nuestro blog.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de AntiguoRincon.com Historia, cultura y curiosidades.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antiguorinconcom\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-30T17:05:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/20200208_145241-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1791\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rafa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@antiguorincon\" \/>\n<meta name=\"twitter:site\" content=\"@antiguorincon\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rafa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/\"},\"author\":{\"name\":\"rafa\",\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/#\\\/schema\\\/person\\\/196cf451e97f5dc8fc15d66c0e365246\"},\"headline\":\"Descubre las terribles historias m\u00e9dicas de siglos pasados\",\"datePublished\":\"2021-08-30T17:05:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/\"},\"wordCount\":1004,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/20200208_145241-scaled.jpg\",\"keywords\":[\"curiosidades m\u00e9dicas\",\"historia de la medicina\",\"historias terribles\",\"medicina\",\"m\u00e9dicos\",\"terrible\"],\"articleSection\":[\"Curiosidades\",\"Edad Contempor\u00e1nea s. XIX-XX\",\"Historia Medicina\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/\",\"url\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/\",\"name\":\"Descubre las terribles historias m\u00e9dicas de siglos pasados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/20200208_145241-scaled.jpg\",\"datePublished\":\"2021-08-30T17:05:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/#\\\/schema\\\/person\\\/196cf451e97f5dc8fc15d66c0e365246\"},\"description\":\"Te acercamos las terribles historias m\u00e9dicas del pasado. Descubre c\u00f3mo eran las mesas de operaciones, el material de los m\u00e9dicos, etc en nuestro blog.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/20200208_145241-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/20200208_145241-scaled.jpg\",\"width\":2560,\"height\":1791},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/descubre-las-terribles-historias-medicas-de-siglos-pasados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descubre las terribles historias m\u00e9dicas de siglos pasados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/\",\"name\":\"Blog AntiguoRincon.com\",\"description\":\"Blog de AntiguoRincon.com  Historia, cultura y curiosidades.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.antiguorincon.com\\\/blog\\\/#\\\/schema\\\/person\\\/196cf451e97f5dc8fc15d66c0e365246\",\"name\":\"rafa\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descubre las terribles historias m\u00e9dicas de siglos pasados","description":"Te acercamos las terribles historias m\u00e9dicas del pasado. Descubre c\u00f3mo eran las mesas de operaciones, el material de los m\u00e9dicos, etc en nuestro blog.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/","og_locale":"es_ES","og_type":"article","og_title":"Descubre las terribles historias m\u00e9dicas de siglos pasados","og_description":"Te acercamos las terribles historias m\u00e9dicas del pasado. Descubre c\u00f3mo eran las mesas de operaciones, el material de los m\u00e9dicos, etc en nuestro blog.","og_url":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/","og_site_name":"Blog de AntiguoRincon.com Historia, cultura y curiosidades.","article_publisher":"https:\/\/www.facebook.com\/antiguorinconcom","article_published_time":"2021-08-30T17:05:03+00:00","og_image":[{"width":2560,"height":1791,"url":"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/20200208_145241-scaled.jpg","type":"image\/jpeg"}],"author":"rafa","twitter_card":"summary_large_image","twitter_creator":"@antiguorincon","twitter_site":"@antiguorincon","twitter_misc":{"Escrito por":"rafa","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/#article","isPartOf":{"@id":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/"},"author":{"name":"rafa","@id":"https:\/\/www.antiguorincon.com\/blog\/#\/schema\/person\/196cf451e97f5dc8fc15d66c0e365246"},"headline":"Descubre las terribles historias m\u00e9dicas de siglos pasados","datePublished":"2021-08-30T17:05:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/"},"wordCount":1004,"commentCount":0,"image":{"@id":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/20200208_145241-scaled.jpg","keywords":["curiosidades m\u00e9dicas","historia de la medicina","historias terribles","medicina","m\u00e9dicos","terrible"],"articleSection":["Curiosidades","Edad Contempor\u00e1nea s. XIX-XX","Historia Medicina"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/","url":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/","name":"Descubre las terribles historias m\u00e9dicas de siglos pasados","isPartOf":{"@id":"https:\/\/www.antiguorincon.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/#primaryimage"},"image":{"@id":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/20200208_145241-scaled.jpg","datePublished":"2021-08-30T17:05:03+00:00","author":{"@id":"https:\/\/www.antiguorincon.com\/blog\/#\/schema\/person\/196cf451e97f5dc8fc15d66c0e365246"},"description":"Te acercamos las terribles historias m\u00e9dicas del pasado. Descubre c\u00f3mo eran las mesas de operaciones, el material de los m\u00e9dicos, etc en nuestro blog.","breadcrumb":{"@id":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/#primaryimage","url":"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/20200208_145241-scaled.jpg","contentUrl":"https:\/\/www.antiguorincon.com\/blog\/wp-content\/uploads\/2020\/05\/20200208_145241-scaled.jpg","width":2560,"height":1791},{"@type":"BreadcrumbList","@id":"https:\/\/www.antiguorincon.com\/blog\/descubre-las-terribles-historias-medicas-de-siglos-pasados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.antiguorincon.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Descubre las terribles historias m\u00e9dicas de siglos pasados"}]},{"@type":"WebSite","@id":"https:\/\/www.antiguorincon.com\/blog\/#website","url":"https:\/\/www.antiguorincon.com\/blog\/","name":"Blog AntiguoRincon.com","description":"Blog de AntiguoRincon.com  Historia, cultura y curiosidades.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.antiguorincon.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.antiguorincon.com\/blog\/#\/schema\/person\/196cf451e97f5dc8fc15d66c0e365246","name":"rafa"}]}},"_links":{"self":[{"href":"https:\/\/www.antiguorincon.com\/blog\/wp-json\/wp\/v2\/posts\/534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.antiguorincon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.antiguorincon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.antiguorincon.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.antiguorincon.com\/blog\/wp-json\/wp\/v2\/comments?post=534"}],"version-history":[{"count":10,"href":"https:\/\/www.antiguorincon.com\/blog\/wp-json\/wp\/v2\/posts\/534\/revisions"}],"predecessor-version":[{"id":556,"href":"https:\/\/www.antiguorincon.com\/blog\/wp-json\/wp\/v2\/posts\/534\/revisions\/556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.antiguorincon.com\/blog\/wp-json\/wp\/v2\/media\/552"}],"wp:attachment":[{"href":"https:\/\/www.antiguorincon.com\/blog\/wp-json\/wp\/v2\/media?parent=534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.antiguorincon.com\/blog\/wp-json\/wp\/v2\/categories?post=534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.antiguorincon.com\/blog\/wp-json\/wp\/v2\/tags?post=534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}